{"id":826,"date":"2021-04-10T12:08:19","date_gmt":"2021-04-10T12:08:19","guid":{"rendered":"https:\/\/freiebaptistenkw.de\/?p=826"},"modified":"2021-04-12T05:30:58","modified_gmt":"2021-04-12T05:30:58","slug":"die-auferstehung-eines-maedchens","status":"publish","type":"post","link":"https:\/\/freiebaptistenkw.de\/index.php\/2021\/04\/10\/die-auferstehung-eines-maedchens\/","title":{"rendered":"Die Auferstehung eines M\u00e4dchens"},"content":{"rendered":"<h1>Matth\u00e4us 9,18-26<\/h1>\n<p><iframe loading=\"lazy\" src=\"https:\/\/anchor.fm\/freiebaptistenkw\/embed\/episodes\/Predigt-von-11-04-2021-Die-Auferstehung-eines-Mdchens-eunp20\" width=\"400px\" height=\"102px\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Die Geschichte, die wir in Matth\u00e4us 9 lesen werden, ist die erste von drei Erweckungen, die Jesus w\u00e4hrend seines Dienstes auf Erden durchgef\u00fchrt hat.<\/p>\n<p>Tats\u00e4chlich beginnt Matth\u00e4us seine Geschichte erst, wenn das M\u00e4dchen bereits tot war. Wir werden jedoch mit der Geschichte in Markus beginnen, um das gesamte Ereignis besser verstehen zu k\u00f6nnen.<\/p>\n<p style=\"padding-left: 40px;\">Und als Jesus im Schiff wieder ans jenseitige Ufer hin\u00fcbergefahren war, versammelte sich eine gro\u00dfe Volksmenge bei ihm; und er war am See. Und siehe, da kam einer der Obersten der Synagoge, namens Jairus; und als er ihn erblickte, warf er sich ihm zu F\u00fc\u00dfen, und er bat ihn sehr und sprach: Mein T\u00f6chterlein liegt in den letzten Z\u00fcgen; komme doch und lege ihr die H\u00e4nde auf, damit sie gesund wird und am Leben bleibt! Und er ging mit ihm; und es folgte ihm eine gro\u00dfe Menge nach, und sie bedr\u00e4ngten ihn. \u2013 Markus 5,21-24<\/p>\n<p>Ein Vergleich mit der Chronologie von Matth\u00e4us stellt diese Ereignis am Anfang von Kapitel 9.<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Jesus war danach in einem Haus und hat gelehrt und Fragen religi\u00f6ser Beamter beantwortet, als er den Gel\u00e4hmten geheilt hat, der durch das Dach zu ihm hinuntergelassen wurde.<\/li>\n<li>Jesus hat dann im Haus von Matth\u00e4us mit mehreren Steuereintreibern gegessen.<\/li>\n<li>Dann kamen die J\u00fcnger Johannes und haben Jesus nach dem Fasten gefragt.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<p>Hier beginnt die Geschichte in Matth\u00e4us.<\/p>\n<blockquote><p><sup>18<\/sup> Und als er dies mit ihnen redete, siehe, da kam ein Vorsteher, fiel vor ihm nieder und sprach: Meine Tochter ist eben gestorben; aber komm und lege deine Hand auf sie, so wird sie leben!<br \/>\n<sup>19<\/sup> Und Jesus stand auf und folgte ihm mit seinen J\u00fcngern.<\/p><\/blockquote>\n<p>Beachte, wie viel Zeit vergangen ist, seit Jairus zum ersten Mal mit Jesus gesprochen hat.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Wahrscheinlich war es mindestens zwei Tage.<\/li>\n<li>Das ist die gleiche Zeit, die Jesus gewartet hat, bevor er geht, als er geh\u00f6rt hat, dass Lazarus krank war.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Es war aber einer krank, Lazarus von Bethanien aus dem Dorf der Maria und ihrer Schwester Martha, n\u00e4mlich der Maria, die den Herrn gesalbt und seine F\u00fc\u00dfe mit ihren Haaren getrocknet hat; deren Bruder Lazarus war krank. Da sandten die Schwestern zu ihm und lie\u00dfen ihm sagen: Herr, siehe, der, den du lieb hast, ist krank! Als Jesus es h\u00f6rte, sprach er: Diese Krankheit ist nicht zum Tode, sondern zur Verherrlichung Gottes, damit der Sohn Gottes dadurch verherrlicht wird! Jesus aber liebte Martha und ihre Schwester und Lazarus. Als er nun h\u00f6rte, dass jener krank sei, blieb er noch zwei Tage an dem Ort, wo er war. \u2013 Johannes 11,1-6<\/p>\n<p>Beachte, dass der Glaube von Jairus mit dem Tod seines Kindes nicht aufgegeben hat.<\/p>\n<p style=\"padding-left: 40px;\">Mein T\u00f6chterlein liegt in den letzten Z\u00fcgen; komme doch und lege ihr die H\u00e4nde auf, damit sie gesund wird und am Leben bleibt! \u2013 Markus 5,23<\/p>\n<p style=\"padding-left: 40px;\">Meine Tochter ist eben gestorben; aber komm und lege deine Hand auf sie, so wird sie leben! \u2013 Matth\u00e4us 9,18<\/p>\n<p>Die Verz\u00f6gerung beim Erreichen des M\u00e4dchens geht weiter.<\/p>\n<blockquote><p><sup>20<\/sup> Und siehe, eine Frau, die zw\u00f6lf Jahre blutfl\u00fcssig war, trat von hinten herzu und r\u00fchrte den Saum seines Gewandes an.<br \/>\n<sup>21<\/sup> Denn sie sagte bei sich selbst: Wenn ich nur sein Gewand anr\u00fchre, so bin ich geheilt!<br \/>\n<sup>22<\/sup> Jesus aber wandte sich um, sah sie und sprach: Sei getrost, meine Tochter! Dein Glaube hat dich gerettet! Und die Frau war geheilt von jener Stunde an.<\/p><\/blockquote>\n<p style=\"padding-left: 40px;\">W\u00e4hrend er noch redete, kamen etliche von den Leuten des Obersten der Synagoge und sprachen: Deine Tochter ist gestorben, was bem\u00fchst du den Meister noch? \u2013 Markus 5,35<\/p>\n<p style=\"padding-left: 40px;\">Da es aber Jesus h\u00f6rte, antwortete er ihm und sprach: F\u00fcrchte dich nicht; glaube nur, so wird sie gerettet werden! \u2013 Lukas 8,50<\/p>\n<p style=\"padding-left: 40px;\">Und er lie\u00df niemand mitgehen als Petrus und Jakobus und Johannes, den Bruder des Jakobus. Und er kommt in das Haus des Obersten der Synagoge und sieht das Get\u00fcmmel, wie sehr sie weinten und heulten. \u2013 Markus 5,37-38<\/p>\n<p>Selbst von den \u00c4rmsten wurde erwartet, dass sie mindestens drei professionelle Trauernde einstellen, um \u00fcber den Verlust eines Familienmitglieds zu weinen und heulen.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Dies ist ein Beweis daf\u00fcr, dass das M\u00e4dchen tot war, da professionelle Trauernde sonst nicht eingestellt w\u00fcrden.<\/li>\n<li>Die Professionellen h\u00e4tten es bemerkt, wenn sie nicht wirklich tot w\u00e4re.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<blockquote><p><sup>23<\/sup> Als nun Jesus in das Haus des Vorstehers kam und die Pfeifer und das Get\u00fcmmel sah,<br \/>\n<sup>24<\/sup> spricht er zu ihnen: Entfernt euch! Denn das M\u00e4dchen ist nicht gestorben, sondern es schl\u00e4ft. Und sie lachten ihn aus.<\/p><\/blockquote>\n<p style=\"padding-left: 40px;\">Und er geht hinein und spricht zu ihnen: Was l\u00e4rmt ihr so und weint? Das Kind ist nicht gestorben, sondern es schl\u00e4ft! \u2013 Markus 5,39<\/p>\n<p style=\"padding-left: 40px;\">Und sie lachten ihn aus, weil sie wussten, dass sie gestorben war. \u2013 Lukas 8,53<\/p>\n<blockquote><p><sup>25<\/sup> Als aber die Menge hinausgetrieben war, ging er hinein und ergriff ihre Hand; und das M\u00e4dchen stand auf.<\/p><\/blockquote>\n<p style=\"padding-left: 40px;\">Nachdem er aber alle hinausgetrieben hatte, nahm er den Vater und die Mutter des Kindes mit sich und die, welche bei ihm waren, und ging hinein, wo das Kind lag. \u2013 Markus 5,40b<\/p>\n<p>Zweifellos hat Jesus den Eltern tr\u00f6stende Worte gesprochen, vielleicht die gleichen, die er zu Martha gesagt hat, bevor er ihren Bruder von den Toten auferweckt hat.<\/p>\n<p style=\"padding-left: 40px;\">Jesus spricht zu ihr: Ich bin die Auferstehung und das Leben. Wer an mich glaubt, wird leben, auch wenn er stirbt; und jeder, der lebt und an mich glaubt, wird in Ewigkeit nicht sterben. Glaubst du das? \u2013 Johannes 11,25-26<\/p>\n<p style=\"padding-left: 40px;\">Und er ergriff die Hand des Kindes und sprach zu ihm: Talita kumi!, das hei\u00dft \u00fcbersetzt: M\u00e4dchen, ich sage dir, steh auf! \u2013 Markus 5,41<\/p>\n<p style=\"padding-left: 40px;\">Und sogleich stand das M\u00e4dchen auf und ging umher; es war n\u00e4mlich zw\u00f6lf Jahre alt. Und sie gerieten au\u00dfer sich vor Staunen. \u2013 Markus 5,42<\/p>\n<p style=\"padding-left: 40px;\">Und ihr Geist kehrte zur\u00fcck, und sie stand augenblicklich auf; und er befahl, ihr zu essen zu geben. Und ihre Eltern gerieten au\u00dfer sich; er aber gebot ihnen, niemand zu sagen, was geschehen war. \u2013 Lukas 8,55-56<\/p>\n<blockquote><p><sup>26<\/sup> Und die Nachricht hiervon verbreitete sich in jener ganzen Gegend.<\/p><\/blockquote>\n<p style=\"padding-left: 40px;\">Ich will euch aber, Br\u00fcder, nicht in Unwissenheit lassen \u00fcber die Entschlafenen, damit ihr nicht traurig seid wie die anderen, die keine Hoffnung haben. Denn wenn wir glauben, dass Jesus gestorben und auferstanden ist, so wird Gott auch die Entschlafenen durch Jesus mit ihm f\u00fchren. Denn das sagen wir euch in einem Wort des Herrn: Wir, die wir leben und bis zur Wiederkunft des Herrn \u00fcbrig bleiben, werden den Entschlafenen nicht zuvorkommen; denn der Herr selbst wird, wenn der Befehl ergeht und die Stimme des Erzengels und die Posaune Gottes erschallt, vom Himmel herabkommen, und die Toten in Christus werden zuerst auferstehen. Danach werden wir, die wir leben und \u00fcbrig bleiben, zusammen mit ihnen entr\u00fcckt werden in Wolken, zur Begegnung mit dem Herrn, in die Luft, und so werden wir bei dem Herrn sein allezeit. So tr\u00f6stet nun einander mit diesen Worten! \u2013 1. Thessalonicher 4,13-18<\/p>\n<p style=\"padding-left: 40px;\">Und ich h\u00f6rte eine Stimme aus dem Himmel, die zu mir sprach: Schreibe: Gl\u00fcckselig sind die Toten, die im Herrn sterben, von nun an! Ja, spricht der Geist, sie sollen ruhen von ihren M\u00fchen; ihre Werke aber folgen ihnen nach. \u2013 Offenbarung 14,13<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Matth\u00e4us 9,18-26 Die Geschichte, die wir in Matth\u00e4us 9 lesen werden, ist die erste von drei Erweckungen, die Jesus w\u00e4hrend seines Dienstes auf Erden durchgef\u00fchrt hat. Tats\u00e4chlich beginnt Matth\u00e4us seine Geschichte erst, wenn das M\u00e4dchen bereits tot war. Wir werden jedoch mit der Geschichte in Markus beginnen, um das gesamte Ereignis besser verstehen zu k\u00f6nnen. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/freiebaptistenkw.de\/index.php\/2021\/04\/10\/die-auferstehung-eines-maedchens\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDie Auferstehung eines M\u00e4dchens\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-826","post","type-post","status-publish","format-standard","hentry","category-matthaeus"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/posts\/826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/comments?post=826"}],"version-history":[{"count":3,"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/posts\/826\/revisions"}],"predecessor-version":[{"id":829,"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/posts\/826\/revisions\/829"}],"wp:attachment":[{"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/media?parent=826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/categories?post=826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freiebaptistenkw.de\/index.php\/wp-json\/wp\/v2\/tags?post=826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}